﻿{"id":958,"date":"2023-11-09T14:00:54","date_gmt":"2023-11-09T11:00:54","guid":{"rendered":"https:\/\/consistanbul.esteri.it\/?p=958"},"modified":"2023-11-21T19:19:13","modified_gmt":"2023-11-21T16:19:13","slug":"viii-settimana-della-cucina-italiana-nel-mondo","status":"publish","type":"post","link":"https:\/\/consistanbul.esteri.it\/it\/news\/dal_consolato\/2023\/11\/viii-settimana-della-cucina-italiana-nel-mondo\/","title":{"rendered":"VIII Settimana della cucina italiana nel mondo"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>SCIM 2023, 13-19 Novembre 2023<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-968 img-fluid\" src=\"https:\/\/consistanbul.esteri.it\/wp-content\/uploads\/2023\/11\/Immagine-settimana-1-300x251.png\" alt=\"\" width=\"112\" height=\"93\" srcset=\"https:\/\/consistanbul.esteri.it\/wp-content\/uploads\/2023\/11\/Immagine-settimana-1-300x251.png 300w, https:\/\/consistanbul.esteri.it\/wp-content\/uploads\/2023\/11\/Immagine-settimana-1-1024x856.png 1024w, https:\/\/consistanbul.esteri.it\/wp-content\/uploads\/2023\/11\/Immagine-settimana-1-768x642.png 768w, https:\/\/consistanbul.esteri.it\/wp-content\/uploads\/2023\/11\/Immagine-settimana-1.png 1134w\" sizes=\"auto, (max-width: 112px) 100vw, 112px\" \/><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Comunicato Stampa<\/strong><\/p>\n<p style=\"text-align: justify;\">Gioved\u00ec 9 novembre, il Consolato Generale d\u2019Italia a Istanbul e la Camera di Commercio e Industria Italiana in Turchia hanno presentato alla stampa il programma della <strong>VIII edizione della Settimana della Cucina Italiana 2023, dal titolo \u201cA tavola con la cucina italiana: il benessere con gusto\u201d<\/strong>. La rassegna, promossa dal Ministero degli Affari Esteri e della Cooperazione Internazionale attraverso le Ambasciate, i Consolati, gli Istituti Italiani di Cultura e gli Uffici ITA, promuove annualmente la cucina e i prodotti agroalimentari italiani di qualit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Il Consolato Generale, con l\u2019Istituto Italiano di Cultura, l\u2019Agenzia Italiana per il Commercio Estero, la Camera di Commercio e Industria Italiana in Turchia, il Comites, Gastronometro, la Societ\u00e0 Operaia di Mutuo Soccorso, il Circolo Roma, il Liceo IMI, organizzano una settimana di attivit\u00e0 di promozione della cultura del mangiare sano e con gusto.<\/p>\n<p style=\"text-align: justify;\">Il programma prevede il pranzo offerto alla stampa dalla Camera di Commercio e Industria italiana, poi, in collaborazione con Gastronometro e lo <strong>Chef Samuele Zaninotto<\/strong>, una Masterclass\/Workshop per gli studenti delle Accademie di Cucina e una cena per gli addetti di settore, con l\u2019Istituto Italiano di Cultura la presentazione del <strong>Libro \u201cTutti i Piatti dei Presidenti\u201d<\/strong> di Lorenza Scalisi, Chiara Cadeddu, e dello Chef Fabrizio Boca, infine, in collaborazione con la Societ\u00e0 Operaia di Mutuo Soccorso, l\u2019evento Aperitivo all&#8217;Italiana per stampa, istituzioni e mondo imprenditoriale. Il 16, i ristoranti Cecconi\u2019s, Filo d\u2019Olio, Il Pellicano, Nello\u2019s, Terrazza Italia e il Circolo Roma, con il Consolato Generale, celebreranno la tradizione di <a href=\"https:\/\/consistanbul.esteri.it\/wp-content\/uploads\/2023\/11\/Giovedi-gnocchi-final.png\"><strong>Gioved\u00ec Gnocchi<\/strong><\/a> presentando un piatto di gnocchi fuori men\u00f9. Il 9 dicembre, in collaborazione con le aziende italiane in Turchia, il Consolato Generale parteciper\u00e0 al mercatino <strong>\u201cPortobello\u201d<\/strong> del Circolo Roma. I prodotti donati saranno venduti e i proventi devoluti alla Societ\u00e0 Italiana di Beneficienza.<\/p>\n<p style=\"text-align: justify;\">\u201c<strong>La Cucina rappresenta uno dei migliori biglietti da visita del nostro paese<\/strong> e poterla celebrare, presentare e promuovere nei paesi dove abbiamo la fortuna di lavorare \u00e8 motivo di orgoglio\u201d ha dichiarato il Console Generale Elena Clemente, \u201ca maggior ragione in Turchia dove la cultura del cibo \u00e8 simile alla nostra e dove la partecipazione delle istituzioni e delle associazioni italiane, delle imprese e dei buongustai di ogni provenienza \u00e8 cos\u00ec entusiasta\u201d.<\/p>\n<p><a href=\"https:\/\/consistanbul.esteri.it\/wp-content\/uploads\/2023\/11\/Programma-Settimana-IT-3.pdf\"><strong>Scarica il programma<\/strong><\/a><\/p>\n<p><strong><a href=\"https:\/\/consistanbul.esteri.it\/wp-content\/uploads\/2023\/11\/Pannello-Sponsor.pdf\">I nostri sponsor<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"SCIM 2023, 13-19 Novembre 2023 Comunicato Stampa Gioved\u00ec 9 novembre, il Consolato Generale d\u2019Italia a Istanbul e la Camera di Commercio e Industria Italiana in Turchia hanno presentato alla stampa il programma della VIII edizione della Settimana della Cucina Italiana 2023, dal titolo \u201cA tavola con la cucina italiana: il benessere con gusto\u201d. La rassegna, [&hellip;]","protected":false},"author":3,"featured_media":968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[12,11],"class_list":["post-958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-diplomazia-culturale","tag-diplomazia-economica"],"_links":{"self":[{"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/posts\/958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=958"}],"version-history":[{"count":5,"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/posts\/958\/revisions"}],"predecessor-version":[{"id":1032,"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/posts\/958\/revisions\/1032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/media\/968"}],"wp:attachment":[{"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=958"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consistanbul.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}